{"id":3491,"date":"2025-11-03T15:03:43","date_gmt":"2025-11-03T14:03:43","guid":{"rendered":"https:\/\/www.esasem.piuinternet.it\/prodotti\/sin categor\u00eda\/bacco-f1\/"},"modified":"2025-11-03T15:03:43","modified_gmt":"2025-11-03T14:03:43","slug":"bacco-f1","status":"publish","type":"product","link":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/","title":{"rendered":"BACCO F1"},"content":{"rendered":"<p><strong>Lamuyo amarillo BACCO tiene una buena capacidad de cuaje con una<\/strong> <strong>producci\u00f3n alta y uniforme<\/strong> durante todo el ciclo. Los frutos son muy regulares con una l<strong>ongitud promedio de 18 &#8211; 20 cm y un ancho de 9 a 10 cm. Excelente<\/strong> <strong>color verde oscuro en la fase del m\u00e1ximo desarrollo y amarillo intenso y brillante<\/strong> durante el cambio de color y la maduraci\u00f3n completa. Los frutos tienen un <strong>peso<\/strong> <strong>promedio de 500-550 g<\/strong> con una pared lisa y pulpa gruesa. Excelente tolerancia al microcracking y muy resistente a la condici\u00f3n de estr\u00e9s y baja temperatura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resistencias:<br \/>\nHR: Tm:0<br \/>\nIR: TSWV:0<\/p>\n","protected":false},"featured_media":3492,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[215,214],"product_tag":[216],"class_list":{"0":"post-3491","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lamuyo","7":"product_cat-pimiento","8":"product_tag-lamuyo-amarillo","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semi di Lamuyo, Pimiento con BACCO F1 - Sementi BACCO F1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semi di Lamuyo, Pimiento con BACCO F1 - Sementi BACCO F1\" \/>\n<meta property=\"og:description\" content=\"Resistencias: HR: Tm:0 IR: TSWV:0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/\" \/>\n<meta property=\"og:site_name\" content=\"Esasem\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esasem.com\/wp-content\/uploads\/2025\/11\/BACCO-F1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"404\" \/>\n\t<meta property=\"og:image:height\" content=\"343\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/\",\"url\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/\",\"name\":\"Semi di Lamuyo, Pimiento con BACCO F1 - Sementi BACCO F1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/BACCO-F1.jpeg\",\"datePublished\":\"2025-11-03T14:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/BACCO-F1.jpeg\",\"contentUrl\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/BACCO-F1.jpeg\",\"width\":404,\"height\":343},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/sementi-per-orto-professionali\\\/bacco-f1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esasem.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"semillas horticolas profesionales\",\"item\":\"https:\\\/\\\/esasem.com\\\/es\\\/semillas-horticolas-profesionales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BACCO F1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esasem.com\\\/es\\\/\",\"name\":\"Esasem\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esasem.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/#organization\",\"name\":\"Esasem\",\"url\":\"https:\\\/\\\/esasem.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-esasem-horiz_web.png\",\"contentUrl\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-esasem-horiz_web.png\",\"width\":412,\"height\":100,\"caption\":\"Esasem\"},\"image\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semi di Lamuyo, Pimiento con BACCO F1 - Sementi BACCO F1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/","og_locale":"es_ES","og_type":"article","og_title":"Semi di Lamuyo, Pimiento con BACCO F1 - Sementi BACCO F1","og_description":"Resistencias: HR: Tm:0 IR: TSWV:0","og_url":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/","og_site_name":"Esasem","og_image":[{"width":404,"height":343,"url":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/11\/BACCO-F1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/","url":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/","name":"Semi di Lamuyo, Pimiento con BACCO F1 - Sementi BACCO F1","isPartOf":{"@id":"https:\/\/esasem.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/#primaryimage"},"image":{"@id":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/#primaryimage"},"thumbnailUrl":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/11\/BACCO-F1.jpeg","datePublished":"2025-11-03T14:03:43+00:00","breadcrumb":{"@id":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/#primaryimage","url":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/11\/BACCO-F1.jpeg","contentUrl":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/11\/BACCO-F1.jpeg","width":404,"height":343},{"@type":"BreadcrumbList","@id":"https:\/\/esasem.com\/es\/sementi-per-orto-professionali\/bacco-f1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/esasem.com\/es\/"},{"@type":"ListItem","position":2,"name":"semillas horticolas profesionales","item":"https:\/\/esasem.com\/es\/semillas-horticolas-profesionales\/"},{"@type":"ListItem","position":3,"name":"BACCO F1"}]},{"@type":"WebSite","@id":"https:\/\/esasem.com\/es\/#website","url":"https:\/\/esasem.com\/es\/","name":"Esasem","description":"","publisher":{"@id":"https:\/\/esasem.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esasem.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esasem.com\/es\/#organization","name":"Esasem","url":"https:\/\/esasem.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esasem.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/logo-esasem-horiz_web.png","contentUrl":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/logo-esasem-horiz_web.png","width":412,"height":100,"caption":"Esasem"},"image":{"@id":"https:\/\/esasem.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/product\/3491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/comments?post=3491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/media\/3492"}],"wp:attachment":[{"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/media?parent=3491"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/product_brand?post=3491"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/product_cat?post=3491"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esasem.com\/es\/wp-json\/wp\/v2\/product_tag?post=3491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}