{"id":3244,"date":"2025-09-30T17:55:39","date_gmt":"2025-09-30T15:55:39","guid":{"rendered":"https:\/\/www.esasem.piuinternet.it\/prodotti\/uncategorized\/palla-rossa-2-preco\/"},"modified":"2025-09-30T17:55:39","modified_gmt":"2025-09-30T15:55:39","slug":"palla-rossa-2-preco","status":"publish","type":"product","link":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/","title":{"rendered":"Palla Rossa 2 &#8211; Preco"},"content":{"rendered":"<p>Compact plant with very early cycle, ripening 60 days after planting, suitable for summer-autumn harvest. Compact head, of good size, weighing 250 g. It shows bright deep red colour and is resistant to bolting. Very good uniformity.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compact plant with very early cycle, ripening 60 days after planting, suitable for summer-autumn harvest. Compact head, of good size, weighing 250 g. It shows bright deep red colour and is resistant to bolting. Very good uniformity.<\/p>\n","protected":false},"featured_media":3245,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[185],"product_tag":[],"class_list":{"0":"post-3244","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chicory","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semi di Chicory con Palla Rossa 2 - Preco - Sementi Palla Rossa 2 - Preco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semi di Chicory con Palla Rossa 2 - Preco - Sementi Palla Rossa 2 - Preco\" \/>\n<meta property=\"og:description\" content=\"Compact plant with very early cycle, ripening 60 days after planting, suitable for summer-autumn harvest. Compact head, of good size, weighing 250 g. It shows bright deep red colour and is resistant to bolting. Very good uniformity.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/\" \/>\n<meta property=\"og:site_name\" content=\"Esasem\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/PALLA-ROSSA-2-PRECO.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"457\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/\",\"url\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/\",\"name\":\"Semi di Chicory con Palla Rossa 2 - Preco - Sementi Palla Rossa 2 - Preco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PALLA-ROSSA-2-PRECO.jpeg\",\"datePublished\":\"2025-09-30T15:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PALLA-ROSSA-2-PRECO.jpeg\",\"contentUrl\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PALLA-ROSSA-2-PRECO.jpeg\",\"width\":457,\"height\":260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/sementi-per-orto-professionali\\\/palla-rossa-2-preco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esasem.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"professional vegetable seeds\",\"item\":\"https:\\\/\\\/esasem.com\\\/sementi-orticole-professionali\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palla Rossa 2 &#8211; Preco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/esasem.com\\\/en\\\/\",\"name\":\"Esasem\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esasem.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/#organization\",\"name\":\"Esasem\",\"url\":\"https:\\\/\\\/esasem.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-esasem-horiz_web.png\",\"contentUrl\":\"https:\\\/\\\/esasem.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-esasem-horiz_web.png\",\"width\":412,\"height\":100,\"caption\":\"Esasem\"},\"image\":{\"@id\":\"https:\\\/\\\/esasem.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semi di Chicory con Palla Rossa 2 - Preco - Sementi Palla Rossa 2 - Preco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/","og_locale":"en_US","og_type":"article","og_title":"Semi di Chicory con Palla Rossa 2 - Preco - Sementi Palla Rossa 2 - Preco","og_description":"Compact plant with very early cycle, ripening 60 days after planting, suitable for summer-autumn harvest. Compact head, of good size, weighing 250 g. It shows bright deep red colour and is resistant to bolting. Very good uniformity.","og_url":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/","og_site_name":"Esasem","og_image":[{"width":457,"height":260,"url":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/PALLA-ROSSA-2-PRECO.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/","url":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/","name":"Semi di Chicory con Palla Rossa 2 - Preco - Sementi Palla Rossa 2 - Preco","isPartOf":{"@id":"https:\/\/esasem.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/#primaryimage"},"image":{"@id":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/#primaryimage"},"thumbnailUrl":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/PALLA-ROSSA-2-PRECO.jpeg","datePublished":"2025-09-30T15:55:39+00:00","breadcrumb":{"@id":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/#primaryimage","url":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/PALLA-ROSSA-2-PRECO.jpeg","contentUrl":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/PALLA-ROSSA-2-PRECO.jpeg","width":457,"height":260},{"@type":"BreadcrumbList","@id":"https:\/\/esasem.com\/en\/sementi-per-orto-professionali\/palla-rossa-2-preco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/esasem.com\/en\/"},{"@type":"ListItem","position":2,"name":"professional vegetable seeds","item":"https:\/\/esasem.com\/sementi-orticole-professionali\/"},{"@type":"ListItem","position":3,"name":"Palla Rossa 2 &#8211; Preco"}]},{"@type":"WebSite","@id":"https:\/\/esasem.com\/en\/#website","url":"https:\/\/esasem.com\/en\/","name":"Esasem","description":"","publisher":{"@id":"https:\/\/esasem.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esasem.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/esasem.com\/en\/#organization","name":"Esasem","url":"https:\/\/esasem.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/esasem.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/logo-esasem-horiz_web.png","contentUrl":"https:\/\/esasem.com\/wp-content\/uploads\/2025\/09\/logo-esasem-horiz_web.png","width":412,"height":100,"caption":"Esasem"},"image":{"@id":"https:\/\/esasem.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/product\/3244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/comments?post=3244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/media\/3245"}],"wp:attachment":[{"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/media?parent=3244"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/product_brand?post=3244"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/product_cat?post=3244"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esasem.com\/en\/wp-json\/wp\/v2\/product_tag?post=3244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}